{"id":3466,"date":"2021-12-03T17:59:41","date_gmt":"2021-12-03T16:59:41","guid":{"rendered":"http:\/\/www.leguidedachatdesvins.eu\/fr\/?p=3466"},"modified":"2021-12-03T17:59:41","modified_gmt":"2021-12-03T16:59:41","slug":"lidl-de-beaux-rapports-qualite-prix","status":"publish","type":"post","link":"https:\/\/www.leguidedachatdesvins.eu\/fr\/2021\/12\/03\/lidl-de-beaux-rapports-qualite-prix\/","title":{"rendered":"LIDL, de beaux rapports qualit\u00e9 \/prix"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"http:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-5.jpg\" alt=\"\" class=\"wp-image-3467\" srcset=\"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-5.jpg 300w, https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-5-270x135.jpg 270w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p><strong>LIDL<\/strong> ne rimait pas avec vins, sauf pour des promotions de courte dur\u00e9e  ax\u00e9es sur Bordeaux. Aujourd&#8217;hui, la cave de LIDL pr\u00e9sente avec le sourire <em>d&#8217;Eline, l&#8217;acheteuse vin<\/em>, <strong>109 produits pr\u00e9sents toute l&#8217;ann\u00e9e<\/strong>. D&#8217;autres bouteilles toujours \u00e0 petits prix suivent les saisons.  Dans les <strong>140 vins provenant de 12 pays<\/strong> ,  (voir  le folder), nous constatons  trop de bouteilles avec simplement le nom du c\u00e9page ou de l&#8217;appellation sans indication de propri\u00e9t\u00e9 ou de  cave. (Chablis, Saint Emilion Grand Cru, Gruner Veltliner&#8230;)<\/p>\n\n\n\n<p>Nous avons choisi <strong>3 super rapports qualit\u00e9\/prix<\/strong>. <\/p>\n\n\n\n<p style=\"font-size:23px\"><strong>Blume Verdejo Seleccion 2020 Pagos del Rey Rueda Espagne<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-1.png\" alt=\"\" class=\"wp-image-3469\" width=\"320\" height=\"446\" srcset=\"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-1.png 640w, https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-1-215x300.png 215w, https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-1-270x376.png 270w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Blume Verdejo Selecci\u00f3n <\/strong>est produit dans notre cave Pagos del Rey, situ\u00e9e dans la province de Valladolid, \u00e0 Rueda. Bien typique du c\u00e9page avec des notes d&#8217;agrumes et de fleurs et une subtile touche d&#8217;aneth . Bouche ronde et fra\u00eeche avec une belle vigueur finale. A boire \u00e0 10\u00b0,avec une lotte aux petits l\u00e9gumes ou des sardines \u00e0 la plancha.<strong>Exceptionnel rapport qualit\u00e9\/prix !<\/strong><\/p>\n\n\n\n<p style=\"font-size:18px\" class=\"has-text-color has-vivid-red-color\">LIDL :4,99\u20ac<\/p>\n\n\n\n<p style=\"font-size:23px\"><strong>Fiano 2020 Duca di Sassera IGT Puglia Italie<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"http:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-4.jpg\" alt=\"\" class=\"wp-image-3472\" srcset=\"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-4.jpg 600w, https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-4-300x225.jpg 300w, https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-4-270x203.jpg 270w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Fiano &#8220;ottenuto da uve Leggermente Appassite<\/strong> &#8221; Les baies du c\u00e9page Fiano sont l\u00e9g\u00e8rement fl\u00e9tries donc concentr\u00e9es. La couleur dor\u00e9e le prouve. Le nez, complexe m\u00e9lange des notes de citrons m\u00fbrs (l\u00e0-bas on parle de bergamote) avec des ar\u00f4mes d&#8217;amandes fra\u00eeches. La bouche est douce et finit sur la fra\u00eecheur. A boire autant sur une volaille que sur un fromage. Un vin original.<\/p>\n\n\n\n<p style=\"font-size:18px\" class=\"has-text-color has-vivid-red-color\">LIDL :5,99\u20ac<\/p>\n\n\n\n<p style=\"font-size:23px\"><strong>Ch\u00e2teau Le Cassanet 2020 Haut -M\u00e9doc<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-6.jpg\" alt=\"\" class=\"wp-image-3475\" width=\"134\" height=\"472\" srcset=\"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-6.jpg 162w, https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-content\/uploads\/2021\/12\/external-content.duckduckgo-6-85x300.jpg 85w\" sizes=\"auto, (max-width: 134px) 100vw, 134px\" \/><\/figure><\/div>\n\n\n\n<p>80% de merlot et 20% de cabernet sauvignon pour un vin classique de Bordeaux Fruits noirs, cassis, bouche harmonieuse avec la rondeur du merlot  et finale plut\u00f4t courte. Un vin qui plaira \u00e0 tous. Servir \u00e0 17 degr\u00e9s.<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-red-color\">LIDL : 6,99\u20ac<\/p>\n\n\n\n<p style=\"font-size:18px\"><em>Les bulles s\u00e9lectionn\u00e9es suivront dans une autre NEWS.<\/em><\/p>\n\n\n\n<p><strong>Jacques Gi\u00e8rs et Patrick Fi\u00e9vez<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIDL ne rimait pas avec vins, sauf pour des promotions de courte dur\u00e9e ax\u00e9es sur Bordeaux. Aujourd&#8217;hui, la cave de LIDL pr\u00e9sente avec le sourire d&#8217;Eline, l&#8217;acheteuse vin, 109 produits&#8230; <a class=\"read-more\" href=\"https:\/\/www.leguidedachatdesvins.eu\/fr\/2021\/12\/03\/lidl-de-beaux-rapports-qualite-prix\/\">[Continuer la lecture]<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3466","post","type-post","status-publish","format-standard","hentry","category-degustations","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/posts\/3466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/comments?post=3466"}],"version-history":[{"count":5,"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/posts\/3466\/revisions"}],"predecessor-version":[{"id":3478,"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/posts\/3466\/revisions\/3478"}],"wp:attachment":[{"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/media?parent=3466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/categories?post=3466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leguidedachatdesvins.eu\/fr\/wp-json\/wp\/v2\/tags?post=3466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}